{"id":28,"date":"2018-01-06T00:21:31","date_gmt":"2018-01-06T00:21:31","guid":{"rendered":"http:\/\/www.vzschrudim.cz\/?page_id=28"},"modified":"2019-07-01T16:30:18","modified_gmt":"2019-07-01T16:30:18","slug":"fotoalbum","status":"publish","type":"page","link":"https:\/\/www.vzschrudim.cz\/index.php\/fotoalbum\/","title":{"rendered":"Fotoalbum"},"content":{"rendered":"ngg_shortcode_0_placeholder\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-28","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.vzschrudim.cz\/index.php\/wp-json\/wp\/v2\/pages\/28","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vzschrudim.cz\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.vzschrudim.cz\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.vzschrudim.cz\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vzschrudim.cz\/index.php\/wp-json\/wp\/v2\/comments?post=28"}],"version-history":[{"count":25,"href":"https:\/\/www.vzschrudim.cz\/index.php\/wp-json\/wp\/v2\/pages\/28\/revisions"}],"predecessor-version":[{"id":150,"href":"https:\/\/www.vzschrudim.cz\/index.php\/wp-json\/wp\/v2\/pages\/28\/revisions\/150"}],"wp:attachment":[{"href":"https:\/\/www.vzschrudim.cz\/index.php\/wp-json\/wp\/v2\/media?parent=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}